{"id":1509682,"date":"2025-03-12T12:21:21","date_gmt":"2025-03-12T11:21:21","guid":{"rendered":"https:\/\/prilux.es\/portfolio-item\/iluminacao-dinamica-da-torre-del-agua-em-pilas-sevilla\/"},"modified":"2025-03-12T12:21:21","modified_gmt":"2025-03-12T11:21:21","slug":"iluminacao-dinamica-da-torre-del-agua-em-pilas-sevilla","status":"publish","type":"portfolio","link":"https:\/\/prilux.es\/pt-pt\/portfolio-item\/iluminacao-dinamica-da-torre-del-agua-em-pilas-sevilla\/","title":{"rendered":"Ilumina\u00e7\u00e3o din\u00e2mica da Torre del Agua em Pilas (Sevilla)"},"content":{"rendered":"<p><a href=\"https:\/\/prilux.es\/pt-pt\/portfolio-item\/iluminacao-dinamica-da-torre-del-agua-em-pilas-sevilla\/\">https:\/\/prilux.es\/portfolio-item\/iluminacion-dinamica-en-pilas\/<\/a><\/p>\n<p><a href=\"https:\/\/prilux.es\/pt-pt\/portfolio-item\/iluminacao-dinamica-da-torre-del-agua-em-pilas-sevilla\/\">Iluminaci\u00f3n din\u00e1mica en Pilas<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>https:\/\/prilux.es\/portfolio-item\/iluminacion-dinamica-en-pilas\/ Iluminaci\u00f3n din\u00e1mica en Pilas<\/p>\n","protected":false},"author":2,"featured_media":1509001,"menu_order":0,"template":"","etiqueta_portfolio":[24557],"familia_portfolio":[24509],"pais_portfolio":[24469],"provincia_portfolio":[25414],"portfolio-types":[24487],"class_list":["post-1509682","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","etiqueta_portfolio-led-pad-rgbw-pt-pt","familia_portfolio-fatos-de-banho","pais_portfolio-espana-pt-pt","provincia_portfolio-sevilla-pt-pt","portfolio-types-iluminacao-arquitetonica"],"acf":{"descripcion_para_caract_tecnicas":"O resultado \u00e9 uma ilumina\u00e7\u00e3o din\u00e2mica que n\u00e3o s\u00f3 valoriza a arquitetura da Torre de \u00c1gua, mas tamb\u00e9m a torna um elemento vivo dentro de Pilas. A possibilidade de ajustar a ilumina\u00e7\u00e3o em tempo real permite uma maior intera\u00e7\u00e3o com os habitantes, oferecendo uma experi\u00eancia visual marcante e em constante evolu\u00e7\u00e3o. Al\u00e9m disso, a integra\u00e7\u00e3o com o sistema de telegest\u00e3o municipal garante efici\u00eancia e sustentabilidade, optimizando o consumo de energia. Este projeto \u00e9 um exemplo claro de como a inova\u00e7\u00e3o na ilumina\u00e7\u00e3o pode valorizar o patrim\u00f3nio e refor\u00e7ar a identidade de um munic\u00edpio.   ","titulo_para_caract_tecnicas":"Resultados: Um espa\u00e7o iluminado que evolui com a cidade","categoria_portfolio_principal":"Ilumina\u00e7\u00e3o arquitet\u00f3nica","pais_portfolio":"Espa\u00f1a","provincia_portfolio":"Sevilla","titulo_para_necesidad":"Ilumina\u00e7\u00e3o din\u00e2mica da Torre del Agua em Pilas (Sevilla)","descripcion_para_necesidad":"A Torre del Agua de Pilas, antigo dep\u00f3sito de \u00e1gua e s\u00edmbolo do munic\u00edpio, foi objeto de um projeto de revitaliza\u00e7\u00e3o para lhe dar uma nova vida, tanto em termos de utiliza\u00e7\u00e3o como de imagem. No interior, foi criado um centro multifuncional, enquanto no exterior foi implementado um sistema de ilumina\u00e7\u00e3o din\u00e2mico destinado a real\u00e7ar o seu valor patrimonial e a estabelecer uma liga\u00e7\u00e3o com o p\u00fablico. A necessidade era clara: dotar a torre de uma ilumina\u00e7\u00e3o decorativa, vers\u00e1til e control\u00e1vel \u00e0 dist\u00e2ncia, permitindo a sua integra\u00e7\u00e3o no sistema de telegest\u00e3o municipal.  ","titulo_para_solucion":"Solu\u00e7\u00e3o implementada: Ilumina\u00e7\u00e3o vers\u00e1til com controlo inteligente","descripcion_para_solucion":"Para o efeito, foram instalados 39 LED PAD RGBW com sistema de controlo Casambi, que permite a programa\u00e7\u00e3o de cenas de ilumina\u00e7\u00e3o \u00e0 dist\u00e2ncia atrav\u00e9s de Gateway e cart\u00e3o SIM. Esta solu\u00e7\u00e3o proporciona dinamismo e flexibilidade, permitindo que as cores e os efeitos da ilumina\u00e7\u00e3o sejam modificados de acordo com eventos, festividades ou necessidades espec\u00edficas do munic\u00edpio. A tecnologia RGBW cria atmosferas \u00fanicas, adaptando a ilumina\u00e7\u00e3o a cada ocasi\u00e3o e transformando a torre num marco visual na paisagem urbana.  ","galeria solucion":[{"ID":1508966,"id":1508966,"title":"4G1A4315","filename":"4G1A4315.jpg","filesize":222839,"url":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4315.jpg","link":"https:\/\/prilux.es\/pt-pt\/portfolio-item\/iluminacao-dinamica-da-torre-del-agua-em-pilas-sevilla\/4g1a4315-2\/","alt":"","author":"2","description":"","caption":"","name":"4g1a4315-2","status":"inherit","uploaded_to":1509682,"date":"2025-03-12 10:41:51","modified":"2025-03-12 13:36:42","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/prilux.es\/wp-includes\/images\/media\/default.png","width":1620,"height":1080,"sizes":{"thumbnail":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4315-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4315-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4315-768x512.jpg","medium_large-width":640,"medium_large-height":427,"large":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4315-1024x683.jpg","large-width":640,"large-height":427,"1536x1536":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4315-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4315.jpg","2048x2048-width":1620,"2048x2048-height":1080,"pix-blog-small":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4315-622x400.jpg","pix-blog-small-width":622,"pix-blog-small-height":400,"pix-portfolio-small":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4315-600x450.jpg","pix-portfolio-small-width":600,"pix-portfolio-small-height":450,"pix-big":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4315-600x450.jpg","pix-big-width":600,"pix-big-height":450,"pix-square-sm":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4315-400x400.jpg","pix-square-sm-width":400,"pix-square-sm-height":400,"pix-woocommerce-xs":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4315-75x75.jpg","pix-woocommerce-xs-width":75,"pix-woocommerce-xs-height":75,"pix-woocommerce-md":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4315-460x460.jpg","pix-woocommerce-md-width":460,"pix-woocommerce-md-height":460,"pix-xxl":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4315.jpg","pix-xxl-width":1620,"pix-xxl-height":1080,"woocommerce_thumbnail":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4315-300x300.jpg","woocommerce_thumbnail-width":300,"woocommerce_thumbnail-height":300,"woocommerce_single":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4315-600x400.jpg","woocommerce_single-width":600,"woocommerce_single-height":400,"woocommerce_gallery_thumbnail":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4315-100x100.jpg","woocommerce_gallery_thumbnail-width":100,"woocommerce_gallery_thumbnail-height":100}},{"ID":1509001,"id":1509001,"title":"4G1A4510","filename":"4G1A4510.jpg","filesize":562981,"url":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4510.jpg","link":"https:\/\/prilux.es\/pt-pt\/portfolio-item\/iluminacao-dinamica-da-torre-del-agua-em-pilas-sevilla\/4g1a4510-2\/","alt":"","author":"2","description":"","caption":"","name":"4g1a4510-2","status":"inherit","uploaded_to":1509682,"date":"2025-03-12 10:42:22","modified":"2025-03-12 13:36:42","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/prilux.es\/wp-includes\/images\/media\/default.png","width":1620,"height":1080,"sizes":{"thumbnail":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4510-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4510-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4510-768x512.jpg","medium_large-width":640,"medium_large-height":427,"large":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4510-1024x683.jpg","large-width":640,"large-height":427,"1536x1536":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4510-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4510.jpg","2048x2048-width":1620,"2048x2048-height":1080,"pix-blog-small":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4510-622x400.jpg","pix-blog-small-width":622,"pix-blog-small-height":400,"pix-portfolio-small":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4510-600x450.jpg","pix-portfolio-small-width":600,"pix-portfolio-small-height":450,"pix-big":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4510-600x450.jpg","pix-big-width":600,"pix-big-height":450,"pix-square-sm":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4510-400x400.jpg","pix-square-sm-width":400,"pix-square-sm-height":400,"pix-woocommerce-xs":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4510-75x75.jpg","pix-woocommerce-xs-width":75,"pix-woocommerce-xs-height":75,"pix-woocommerce-md":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4510-460x460.jpg","pix-woocommerce-md-width":460,"pix-woocommerce-md-height":460,"pix-xxl":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4510.jpg","pix-xxl-width":1620,"pix-xxl-height":1080,"woocommerce_thumbnail":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4510-300x300.jpg","woocommerce_thumbnail-width":300,"woocommerce_thumbnail-height":300,"woocommerce_single":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4510-600x400.jpg","woocommerce_single-width":600,"woocommerce_single-height":400,"woocommerce_gallery_thumbnail":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4510-100x100.jpg","woocommerce_gallery_thumbnail-width":100,"woocommerce_gallery_thumbnail-height":100}},{"ID":1509010,"id":1509010,"title":"4G1A4512","filename":"4G1A4512.jpg","filesize":339594,"url":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4512.jpg","link":"https:\/\/prilux.es\/pt-pt\/portfolio-item\/iluminacao-dinamica-da-torre-del-agua-em-pilas-sevilla\/4g1a4512-2\/","alt":"","author":"2","description":"","caption":"","name":"4g1a4512-2","status":"inherit","uploaded_to":1509682,"date":"2025-03-12 10:42:31","modified":"2025-03-12 13:36:42","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/prilux.es\/wp-includes\/images\/media\/default.png","width":1620,"height":1080,"sizes":{"thumbnail":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4512-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4512-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4512-768x512.jpg","medium_large-width":640,"medium_large-height":427,"large":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4512-1024x683.jpg","large-width":640,"large-height":427,"1536x1536":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4512-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4512.jpg","2048x2048-width":1620,"2048x2048-height":1080,"pix-blog-small":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4512-622x400.jpg","pix-blog-small-width":622,"pix-blog-small-height":400,"pix-portfolio-small":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4512-600x450.jpg","pix-portfolio-small-width":600,"pix-portfolio-small-height":450,"pix-big":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4512-600x450.jpg","pix-big-width":600,"pix-big-height":450,"pix-square-sm":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4512-400x400.jpg","pix-square-sm-width":400,"pix-square-sm-height":400,"pix-woocommerce-xs":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4512-75x75.jpg","pix-woocommerce-xs-width":75,"pix-woocommerce-xs-height":75,"pix-woocommerce-md":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4512-460x460.jpg","pix-woocommerce-md-width":460,"pix-woocommerce-md-height":460,"pix-xxl":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4512.jpg","pix-xxl-width":1620,"pix-xxl-height":1080,"woocommerce_thumbnail":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4512-300x300.jpg","woocommerce_thumbnail-width":300,"woocommerce_thumbnail-height":300,"woocommerce_single":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4512-600x400.jpg","woocommerce_single-width":600,"woocommerce_single-height":400,"woocommerce_gallery_thumbnail":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4512-100x100.jpg","woocommerce_gallery_thumbnail-width":100,"woocommerce_gallery_thumbnail-height":100}},{"ID":1509014,"id":1509014,"title":"4G1A4516","filename":"4G1A4516.jpg","filesize":360425,"url":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4516.jpg","link":"https:\/\/prilux.es\/pt-pt\/portfolio-item\/iluminacao-dinamica-da-torre-del-agua-em-pilas-sevilla\/4g1a4516-2\/","alt":"","author":"2","description":"","caption":"","name":"4g1a4516-2","status":"inherit","uploaded_to":1509682,"date":"2025-03-12 10:42:37","modified":"2025-03-12 13:36:42","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/prilux.es\/wp-includes\/images\/media\/default.png","width":1620,"height":1080,"sizes":{"thumbnail":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4516-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4516-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4516-768x512.jpg","medium_large-width":640,"medium_large-height":427,"large":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4516-1024x683.jpg","large-width":640,"large-height":427,"1536x1536":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4516-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4516.jpg","2048x2048-width":1620,"2048x2048-height":1080,"pix-blog-small":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4516-622x400.jpg","pix-blog-small-width":622,"pix-blog-small-height":400,"pix-portfolio-small":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4516-600x450.jpg","pix-portfolio-small-width":600,"pix-portfolio-small-height":450,"pix-big":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4516-600x450.jpg","pix-big-width":600,"pix-big-height":450,"pix-square-sm":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4516-400x400.jpg","pix-square-sm-width":400,"pix-square-sm-height":400,"pix-woocommerce-xs":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4516-75x75.jpg","pix-woocommerce-xs-width":75,"pix-woocommerce-xs-height":75,"pix-woocommerce-md":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4516-460x460.jpg","pix-woocommerce-md-width":460,"pix-woocommerce-md-height":460,"pix-xxl":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4516.jpg","pix-xxl-width":1620,"pix-xxl-height":1080,"woocommerce_thumbnail":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4516-300x300.jpg","woocommerce_thumbnail-width":300,"woocommerce_thumbnail-height":300,"woocommerce_single":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4516-600x400.jpg","woocommerce_single-width":600,"woocommerce_single-height":400,"woocommerce_gallery_thumbnail":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4516-100x100.jpg","woocommerce_gallery_thumbnail-width":100,"woocommerce_gallery_thumbnail-height":100}},{"ID":1509018,"id":1509018,"title":"4G1A4517","filename":"4G1A4517.jpg","filesize":397661,"url":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4517.jpg","link":"https:\/\/prilux.es\/pt-pt\/portfolio-item\/iluminacao-dinamica-da-torre-del-agua-em-pilas-sevilla\/4g1a4517-2\/","alt":"","author":"2","description":"","caption":"","name":"4g1a4517-2","status":"inherit","uploaded_to":1509682,"date":"2025-03-12 10:42:43","modified":"2025-03-12 13:36:42","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/prilux.es\/wp-includes\/images\/media\/default.png","width":1620,"height":1080,"sizes":{"thumbnail":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4517-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4517-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4517-768x512.jpg","medium_large-width":640,"medium_large-height":427,"large":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4517-1024x683.jpg","large-width":640,"large-height":427,"1536x1536":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4517-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4517.jpg","2048x2048-width":1620,"2048x2048-height":1080,"pix-blog-small":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4517-622x400.jpg","pix-blog-small-width":622,"pix-blog-small-height":400,"pix-portfolio-small":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4517-600x450.jpg","pix-portfolio-small-width":600,"pix-portfolio-small-height":450,"pix-big":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4517-600x450.jpg","pix-big-width":600,"pix-big-height":450,"pix-square-sm":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4517-400x400.jpg","pix-square-sm-width":400,"pix-square-sm-height":400,"pix-woocommerce-xs":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4517-75x75.jpg","pix-woocommerce-xs-width":75,"pix-woocommerce-xs-height":75,"pix-woocommerce-md":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4517-460x460.jpg","pix-woocommerce-md-width":460,"pix-woocommerce-md-height":460,"pix-xxl":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4517.jpg","pix-xxl-width":1620,"pix-xxl-height":1080,"woocommerce_thumbnail":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4517-300x300.jpg","woocommerce_thumbnail-width":300,"woocommerce_thumbnail-height":300,"woocommerce_single":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4517-600x400.jpg","woocommerce_single-width":600,"woocommerce_single-height":400,"woocommerce_gallery_thumbnail":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4517-100x100.jpg","woocommerce_gallery_thumbnail-width":100,"woocommerce_gallery_thumbnail-height":100}},{"ID":1509022,"id":1509022,"title":"4G1A4520","filename":"4G1A4520.jpg","filesize":341947,"url":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4520.jpg","link":"https:\/\/prilux.es\/pt-pt\/portfolio-item\/iluminacao-dinamica-da-torre-del-agua-em-pilas-sevilla\/4g1a4520-2\/","alt":"","author":"2","description":"","caption":"","name":"4g1a4520-2","status":"inherit","uploaded_to":1509682,"date":"2025-03-12 10:42:49","modified":"2025-03-12 13:36:42","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/prilux.es\/wp-includes\/images\/media\/default.png","width":1620,"height":1080,"sizes":{"thumbnail":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4520-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4520-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4520-768x512.jpg","medium_large-width":640,"medium_large-height":427,"large":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4520-1024x683.jpg","large-width":640,"large-height":427,"1536x1536":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4520-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4520.jpg","2048x2048-width":1620,"2048x2048-height":1080,"pix-blog-small":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4520-622x400.jpg","pix-blog-small-width":622,"pix-blog-small-height":400,"pix-portfolio-small":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4520-600x450.jpg","pix-portfolio-small-width":600,"pix-portfolio-small-height":450,"pix-big":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4520-600x450.jpg","pix-big-width":600,"pix-big-height":450,"pix-square-sm":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4520-400x400.jpg","pix-square-sm-width":400,"pix-square-sm-height":400,"pix-woocommerce-xs":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4520-75x75.jpg","pix-woocommerce-xs-width":75,"pix-woocommerce-xs-height":75,"pix-woocommerce-md":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4520-460x460.jpg","pix-woocommerce-md-width":460,"pix-woocommerce-md-height":460,"pix-xxl":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4520.jpg","pix-xxl-width":1620,"pix-xxl-height":1080,"woocommerce_thumbnail":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4520-300x300.jpg","woocommerce_thumbnail-width":300,"woocommerce_thumbnail-height":300,"woocommerce_single":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4520-600x400.jpg","woocommerce_single-width":600,"woocommerce_single-height":400,"woocommerce_gallery_thumbnail":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4520-100x100.jpg","woocommerce_gallery_thumbnail-width":100,"woocommerce_gallery_thumbnail-height":100}},{"ID":1509026,"id":1509026,"title":"4G1A4522","filename":"4G1A4522.jpg","filesize":330640,"url":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4522.jpg","link":"https:\/\/prilux.es\/pt-pt\/portfolio-item\/iluminacao-dinamica-da-torre-del-agua-em-pilas-sevilla\/4g1a4522-2\/","alt":"","author":"2","description":"","caption":"","name":"4g1a4522-2","status":"inherit","uploaded_to":1509682,"date":"2025-03-12 10:42:56","modified":"2025-03-12 13:36:42","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/prilux.es\/wp-includes\/images\/media\/default.png","width":1620,"height":1080,"sizes":{"thumbnail":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4522-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4522-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4522-768x512.jpg","medium_large-width":640,"medium_large-height":427,"large":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4522-1024x683.jpg","large-width":640,"large-height":427,"1536x1536":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4522-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4522.jpg","2048x2048-width":1620,"2048x2048-height":1080,"pix-blog-small":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4522-622x400.jpg","pix-blog-small-width":622,"pix-blog-small-height":400,"pix-portfolio-small":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4522-600x450.jpg","pix-portfolio-small-width":600,"pix-portfolio-small-height":450,"pix-big":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4522-600x450.jpg","pix-big-width":600,"pix-big-height":450,"pix-square-sm":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4522-400x400.jpg","pix-square-sm-width":400,"pix-square-sm-height":400,"pix-woocommerce-xs":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4522-75x75.jpg","pix-woocommerce-xs-width":75,"pix-woocommerce-xs-height":75,"pix-woocommerce-md":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4522-460x460.jpg","pix-woocommerce-md-width":460,"pix-woocommerce-md-height":460,"pix-xxl":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4522.jpg","pix-xxl-width":1620,"pix-xxl-height":1080,"woocommerce_thumbnail":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4522-300x300.jpg","woocommerce_thumbnail-width":300,"woocommerce_thumbnail-height":300,"woocommerce_single":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4522-600x400.jpg","woocommerce_single-width":600,"woocommerce_single-height":400,"woocommerce_gallery_thumbnail":"https:\/\/prilux.es\/wp-content\/uploads\/2025\/03\/4G1A4522-100x100.jpg","woocommerce_gallery_thumbnail-width":100,"woocommerce_gallery_thumbnail-height":100}}],"imagen_necesidad":false,"icono_categoria_principal":false,"imagen_bajo_solucion":false},"_links":{"self":[{"href":"https:\/\/prilux.es\/pt-pt\/wp-json\/wp\/v2\/portfolio\/1509682","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/prilux.es\/pt-pt\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/prilux.es\/pt-pt\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/prilux.es\/pt-pt\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":0,"href":"https:\/\/prilux.es\/pt-pt\/wp-json\/wp\/v2\/portfolio\/1509682\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/prilux.es\/pt-pt\/wp-json\/wp\/v2\/media\/1509001"}],"wp:attachment":[{"href":"https:\/\/prilux.es\/pt-pt\/wp-json\/wp\/v2\/media?parent=1509682"}],"wp:term":[{"taxonomy":"etiqueta_portfolio","embeddable":true,"href":"https:\/\/prilux.es\/pt-pt\/wp-json\/wp\/v2\/etiqueta_portfolio?post=1509682"},{"taxonomy":"familia_portfolio","embeddable":true,"href":"https:\/\/prilux.es\/pt-pt\/wp-json\/wp\/v2\/familia_portfolio?post=1509682"},{"taxonomy":"pais_portfolio","embeddable":true,"href":"https:\/\/prilux.es\/pt-pt\/wp-json\/wp\/v2\/pais_portfolio?post=1509682"},{"taxonomy":"provincia_portfolio","embeddable":true,"href":"https:\/\/prilux.es\/pt-pt\/wp-json\/wp\/v2\/provincia_portfolio?post=1509682"},{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/prilux.es\/pt-pt\/wp-json\/wp\/v2\/portfolio-types?post=1509682"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}